{"id":5204,"date":"2024-09-10T14:44:45","date_gmt":"2024-09-10T12:44:45","guid":{"rendered":"https:\/\/www.iidh.org\/informacion-legal\/"},"modified":"2024-10-10T16:33:08","modified_gmt":"2024-10-10T14:33:08","slug":"informacion-legal","status":"publish","type":"page","link":"https:\/\/www.iidh.org\/es\/informacion-legal\/","title":{"rendered":"Informaci\u00f3n legal"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-bottom:50px;--awb-margin-top:50px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 1200px + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:58;line-height:var(--awb-typography1-line-height);\">Informaci\u00f3n <strong>legal<\/strong><\/h1><\/div><div class=\"fusion-separator\" style=\"align-self: flex-start;margin-right:auto;margin-bottom:40px;width:100%;max-width:30%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#d00a11;border-color:#d00a11;border-top-width:4px;\"><\/div><\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:17px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color1);--awb-title-color:#212934;--awb-content-color:var(--awb-color8);--awb-icon-box-color:#212934;--awb-toggle-hover-accent-color:#d00a11;--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:26px;--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-5204-1\"><div class=\"fusion-panel panel-default panel-a2fb459e7899bec4a fusion-toggle-has-divider\" style=\"--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_a2fb459e7899bec4a\"><a aria-expanded=\"false\" aria-controls=\"a2fb459e7899bec4a\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5204-1\" data-target=\"#a2fb459e7899bec4a\" href=\"#a2fb459e7899bec4a\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Informaci\u00f3n general sobre la FUNDACI\u00d3N REN\u00c9 CASSIN - INSTITUTO INTERNACIONAL DE DERECHOS HUMANOS<\/span><\/a><\/h4><\/div><div id=\"a2fb459e7899bec4a\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_a2fb459e7899bec4a\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>FONDATION REN\u00c9 CASSIN &#8211; INSTITUT INTERNATIONAL DES DROITS DE L&#8217;HOMME Sede social: 2 all\u00e9e Ren\u00e9 Cassin 67000 Estrasburgo, Francia SIRET: (asociaci\u00f3n) Director de publicaciones: Sr. Sebastien TOUZE El sitio web iidh.org est\u00e1 alojado en : OVH, 2 rue Kellermann &#8211; 59100 Roubaix &#8211; Francia<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-5c605b63d1942671a fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_5c605b63d1942671a\"><a aria-expanded=\"false\" aria-controls=\"5c605b63d1942671a\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5204-1\" data-target=\"#5c605b63d1942671a\" href=\"#5c605b63d1942671a\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Tramitaci\u00f3n vinculada a la gesti\u00f3n de formularios<\/span><\/a><\/h4><\/div><div id=\"5c605b63d1942671a\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_5c605b63d1942671a\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Cada formulario del sitio web de la FONDATION REN\u00c9 CASSIN &#8211; INSTITUT INTERNATIONAL DES DROITS DE L&#8217;HOMME limita la recogida de datos personales a lo necesario e indica en particular:<\/p>\n<p>&#8211; \u00bfCu\u00e1les son las finalidades de la recogida de estos datos?<\/p>\n<p>&#8211; por qu\u00e9 recopilamos datos sobre ti (licitud);<\/p>\n<p>&#8211; los intereses leg\u00edtimos que podamos tener;<\/p>\n<p>&#8211; si los datos son obligatorios o facultativos para la gesti\u00f3n de tu solicitud (los datos obligatorios est\u00e1n resaltados con un asterisco);<\/p>\n<p>&#8211; qui\u00e9n podr\u00e1 leerlo (en principio, s\u00f3lo la FUNDACI\u00d3N REN\u00c9 CASSIN &#8211; INSTITUT INTERNATIONAL DES DROITS DE L&#8217;HOMME, salvo que se especifique en el formulario que se transmitir\u00e1 a un tercero para gestionar tu solicitud);<\/p>\n<p>&#8211; cu\u00e1nto tiempo se conservan los datos recogidos.<\/p>\n<p>Para cualquier informaci\u00f3n o para ejercer tus derechos en relaci\u00f3n con el tratamiento de datos personales gestionado por la FONDATION REN\u00c9 CASSIN &#8211; INSTITUT INTERNATIONAL DES DROITS DE L&#8217;HOMME, consulta el apartado \u00abC\u00f3mo ejercer tus derechos\u00bb.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-be0ac96de585e6b5e fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_be0ac96de585e6b5e\"><a aria-expanded=\"false\" aria-controls=\"be0ac96de585e6b5e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5204-1\" data-target=\"#be0ac96de585e6b5e\" href=\"#be0ac96de585e6b5e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Tratamiento de la gesti\u00f3n de las relaciones con los clientes<\/span><\/a><\/h4><\/div><div id=\"be0ac96de585e6b5e\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_be0ac96de585e6b5e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Como parte de nuestra relaci\u00f3n con nuestros clientes corporativos, podemos recoger y utilizar informaci\u00f3n relativa a personas que son puntos de contacto dentro de estas empresas. Puede tratarse de datos de identificaci\u00f3n (apellidos, nombre, etc.) o de datos relativos a la vida profesional (n\u00fameros de tel\u00e9fono fijo y\/o m\u00f3vil, direcci\u00f3n de correo electr\u00f3nico, etc.). <\/p>\n<p>Utilizamos esta informaci\u00f3n para gestionar nuestra relaci\u00f3n comercial con las empresas clientes en las que trabajas.<\/p>\n<p>Esta informaci\u00f3n se actualiza cuando se producen cambios: por ejemplo, la identidad y los datos de la persona de contacto pueden cambiar si la persona cuyos datos se registran abandona la empresa.<\/p>\n<p>No se transmiten a terceros.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6b49cc8688e797648 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6b49cc8688e797648\"><a aria-expanded=\"false\" aria-controls=\"6b49cc8688e797648\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5204-1\" data-target=\"#6b49cc8688e797648\" href=\"#6b49cc8688e797648\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Cookies y medici\u00f3n de audiencia<\/span><\/a><\/h4><\/div><div id=\"6b49cc8688e797648\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6b49cc8688e797648\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Una cookie es un archivo de texto enviado a tu navegador por el sitio web que est\u00e1s visitando. Esta cookie se utiliza para almacenar y recopilar informaci\u00f3n, por ejemplo para permitirnos saber qu\u00e9 p\u00e1ginas has visitado, cu\u00e1nto tiempo has permanecido en el sitio, en qu\u00e9 enlace(s) has hecho clic, con qu\u00e9 frecuencia vuelves al sitio, etc. <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-14a3f22b3d542efb4 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_14a3f22b3d542efb4\"><a aria-expanded=\"false\" aria-controls=\"14a3f22b3d542efb4\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5204-1\" data-target=\"#14a3f22b3d542efb4\" href=\"#14a3f22b3d542efb4\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Seguridad del sitio y estad\u00edsticas de visitas<\/span><\/a><\/h4><\/div><div id=\"14a3f22b3d542efb4\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_14a3f22b3d542efb4\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Cuando navegas por este sitio, tu navegador transmite autom\u00e1ticamente la informaci\u00f3n necesaria para la navegaci\u00f3n. Recogemos la siguiente informaci\u00f3n en los registros de conexi\u00f3n con el fin de mejorar y proteger nuestro sitio web: <\/p>\n<p> &#8211; Tu direcci\u00f3n IP &#8211; La fecha y hora de las solicitudes &#8211; El contenido de la solicitud &#8211; El origen de la solicitud &#8211; La cantidad de informaci\u00f3n transmitida como respuesta &#8211; La zona horaria &#8211; Informaci\u00f3n como el sistema operativo o el tipo de navegador utilizado &#8211; El idioma y la versi\u00f3n del navegador<\/p>\n<p>Con el fin de adaptar el sitio a las demandas de sus visitantes, tambi\u00e9n realizamos mediciones, sin que estos datos permitan identificarte:<\/p>\n<p> &#8211; el n\u00famero de visitas, &#8211; el n\u00famero de p\u00e1ginas vistas, &#8211; la actividad de los visitantes en el sitio y la frecuencia con la que vuelven.<\/p>\n<p>Este tratamiento se basa en nuestro inter\u00e9s leg\u00edtimo (art\u00edculo 6 \u00a71 f) RGPD) consistente en permitir la navegaci\u00f3n en este sitio web, mejorarlo y garantizar su estabilidad y seguridad.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-98f5cbb1e08d66dd3 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_98f5cbb1e08d66dd3\"><a aria-expanded=\"false\" aria-controls=\"98f5cbb1e08d66dd3\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5204-1\" data-target=\"#98f5cbb1e08d66dd3\" href=\"#98f5cbb1e08d66dd3\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfCu\u00e1les son tus derechos?<\/span><\/a><\/h4><\/div><div id=\"98f5cbb1e08d66dd3\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_98f5cbb1e08d66dd3\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>De acuerdo con el <a href=\"https:\/\/www.cnil.fr\/fr\/reglement-europeen-protection-donnees\" target=\"_blank\" rel=\"noopener noreferrer\">Reglamento General de Protecci\u00f3n de Datos<\/a> y la <a href=\"https:\/\/www.cnil.fr\/fr\/la-loi-informatique-et-libertes\" target=\"_blank\" rel=\"noopener noreferrer\">Ley<\/a> francesa <a href=\"https:\/\/www.cnil.fr\/fr\/la-loi-informatique-et-libertes\" target=\"_blank\" rel=\"noopener noreferrer\">de Protecci\u00f3n de Datos<\/a>, puedes acceder y\/u obtener una copia de tus datos personales.<br \/> Dependiendo del contexto, tambi\u00e9n puedes<\/p>\n<p> &#8211; oponerte al tratamiento de tus datos, rectificarlos o suprimirlos; &#8211; solicitar la limitaci\u00f3n del tratamiento de tus datos y\/o la portabilidad de los mismos.<\/p>\n<p>Cuando nos hayas dado tu consentimiento para el tratamiento, tienes derecho a retirarlo en cualquier momento.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-4bfa54fa559658e04 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_4bfa54fa559658e04\"><a aria-expanded=\"false\" aria-controls=\"4bfa54fa559658e04\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5204-1\" data-target=\"#4bfa54fa559658e04\" href=\"#4bfa54fa559658e04\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfC\u00f3mo puedes ejercer tus derechos?<\/span><\/a><\/h4><\/div><div id=\"4bfa54fa559658e04\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_4bfa54fa559658e04\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Puedes ejercer tus derechos en cualquier momento poni\u00e9ndote en contacto con nosotros:<\/p>\n<p> &#8211; por correo electr\u00f3nico a contact@iidh.org &#8211; utilizando este formulario de contacto &#8211; por correo postal a la siguiente direcci\u00f3n :<\/p>\n<p> FUNDACI\u00d3N REN\u00c9 CASSIN &#8211; INSTITUTO INTERNACIONAL DE DERECHOS HUMANOS 2 all\u00e9e Ren\u00e9 Cassin 67000 Estrasburgo, Francia<\/p>\n<p>Por razones de seguridad, debes demostrar tu identidad (por ejemplo, facilitando tus apellidos, nombre, n\u00famero de cliente, direcci\u00f3n postal o de correo electr\u00f3nico). Si es necesario, se te puede pedir que proporciones una identificaci\u00f3n v\u00e1lida.<br \/> Si, despu\u00e9s de ponerte en contacto con nosotros, consideras que no se han respetado tus derechos en relaci\u00f3n con tus datos, puedes <a href=\"https:\/\/www.cnil.fr\/fr\/webform\/adresser-une-plainte\" target=\"_blank\" rel=\"noopener noreferrer\">presentar una reclamaci\u00f3n ante la CNIL .<\/a> <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-3e058e424f92f1b28 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_3e058e424f92f1b28\"><a aria-expanded=\"false\" aria-controls=\"3e058e424f92f1b28\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-5204-1\" data-target=\"#3e058e424f92f1b28\" href=\"#3e058e424f92f1b28\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Actualizaci\u00f3n de esta pol\u00edtica<\/span><\/a><\/h4><\/div><div id=\"3e058e424f92f1b28\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_3e058e424f92f1b28\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Cambiamos esta pol\u00edtica de privacidad de vez en cuando. En caso de cambios significativos, publicaremos un aviso destacado en el sitio web. <\/p>\n<p>Tambi\u00e9n te invitamos a releer esta pol\u00edtica de vez en cuando.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5204","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informaci\u00f3n legal - Fondation Ren\u00e9 CASSIN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iidh.org\/es\/informacion-legal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informaci\u00f3n legal - Fondation Ren\u00e9 CASSIN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iidh.org\/es\/informacion-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Ren\u00e9 CASSIN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FondationReneCassin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-10T14:33:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iidh.org\/wp-content\/uploads\/2024\/10\/vignette-iidh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IIDHStrasbourg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/informacion-legal\\\/\",\"url\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/informacion-legal\\\/\",\"name\":\"Informaci\u00f3n legal - Fondation Ren\u00e9 CASSIN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#website\"},\"datePublished\":\"2024-09-10T12:44:45+00:00\",\"dateModified\":\"2024-10-10T14:33:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/informacion-legal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iidh.org\\\/es\\\/informacion-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/informacion-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informaci\u00f3n legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/\",\"name\":\"Fondation Ren\u00e9 CASSIN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#organization\",\"name\":\"Fondation Ren\u00e9 CASSIN\",\"url\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iidh.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/LOGO_FRC-rouge.svg\",\"contentUrl\":\"https:\\\/\\\/www.iidh.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/LOGO_FRC-rouge.svg\",\"width\":699,\"height\":221,\"caption\":\"Fondation Ren\u00e9 CASSIN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FondationReneCassin\\\/\",\"https:\\\/\\\/x.com\\\/IIDHStrasbourg\",\"https:\\\/\\\/www.instagram.com\\\/fondationrenecassin\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informaci\u00f3n legal - Fondation Ren\u00e9 CASSIN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iidh.org\/es\/informacion-legal\/","og_locale":"es_ES","og_type":"article","og_title":"Informaci\u00f3n legal - Fondation Ren\u00e9 CASSIN","og_url":"https:\/\/www.iidh.org\/es\/informacion-legal\/","og_site_name":"Fondation Ren\u00e9 CASSIN","article_publisher":"https:\/\/www.facebook.com\/FondationReneCassin\/","article_modified_time":"2024-10-10T14:33:08+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.iidh.org\/wp-content\/uploads\/2024\/10\/vignette-iidh.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@IIDHStrasbourg","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.iidh.org\/es\/informacion-legal\/","url":"https:\/\/www.iidh.org\/es\/informacion-legal\/","name":"Informaci\u00f3n legal - Fondation Ren\u00e9 CASSIN","isPartOf":{"@id":"https:\/\/www.iidh.org\/es\/#website"},"datePublished":"2024-09-10T12:44:45+00:00","dateModified":"2024-10-10T14:33:08+00:00","breadcrumb":{"@id":"https:\/\/www.iidh.org\/es\/informacion-legal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iidh.org\/es\/informacion-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.iidh.org\/es\/informacion-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.iidh.org\/es\/"},{"@type":"ListItem","position":2,"name":"Informaci\u00f3n legal"}]},{"@type":"WebSite","@id":"https:\/\/www.iidh.org\/es\/#website","url":"https:\/\/www.iidh.org\/es\/","name":"Fondation Ren\u00e9 CASSIN","description":"","publisher":{"@id":"https:\/\/www.iidh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iidh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.iidh.org\/es\/#organization","name":"Fondation Ren\u00e9 CASSIN","url":"https:\/\/www.iidh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iidh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.iidh.org\/wp-content\/uploads\/2024\/09\/LOGO_FRC-rouge.svg","contentUrl":"https:\/\/www.iidh.org\/wp-content\/uploads\/2024\/09\/LOGO_FRC-rouge.svg","width":699,"height":221,"caption":"Fondation Ren\u00e9 CASSIN"},"image":{"@id":"https:\/\/www.iidh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FondationReneCassin\/","https:\/\/x.com\/IIDHStrasbourg","https:\/\/www.instagram.com\/fondationrenecassin\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/pages\/5204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/comments?post=5204"}],"version-history":[{"count":1,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/pages\/5204\/revisions"}],"predecessor-version":[{"id":5210,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/pages\/5204\/revisions\/5210"}],"wp:attachment":[{"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/media?parent=5204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}