{"id":4977,"date":"2023-04-28T07:06:57","date_gmt":"2023-04-28T05:06:57","guid":{"rendered":"https:\/\/www.iidh.org\/fallecimiento-del-presidente-jean-paul-costa\/"},"modified":"2024-11-08T15:17:24","modified_gmt":"2024-11-08T13:17:24","slug":"fallecimiento-del-presidente-jean-paul-costa","status":"publish","type":"post","link":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/","title":{"rendered":"Fallecimiento del Presidente Jean-Paul Costa"},"content":{"rendered":"<div class=\"elementor-element elementor-element-9d63bea elementor-widget elementor-widget-heading\" data-id=\"9d63bea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">JEAN-PAUL COSTA (1941-2023)<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-91164e1 elementor-widget elementor-widget-text-editor\" data-id=\"91164e1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>El fallecimiento de Jean-Paul-Costa, el 27 de abril de 2023, ha vuelto a golpear duramente a nuestra Fundaci\u00f3n. Su sencillez, benevolencia y generosidad le granjearon muchos corazones, y el dolor que siente el equipo que trabaj\u00f3 con \u00e9l durante diez a\u00f1os es inmenso. Es raro ver que una personalidad combine con tanto equilibrio una inteligencia brillante y rigurosa, al servicio de convicciones profundas, y una c\u00e1lida simpat\u00eda hacia los dem\u00e1s, llena de delicadeza, hecha de atenciones espont\u00e1neas y gestos discretos. Era un <em>\u00abhombre honesto<\/em> \u00bb en todos los sentidos de la palabra, un hombre de coraz\u00f3n y un hombre de cultura, un sabio que nunca separ\u00f3 ciencia y conciencia. No pod\u00edas acercarte a \u00e9l sin sentir inmediatamente admiraci\u00f3n, estima y respeto. Su muerte es una p\u00e9rdida personal para todos los que entraron en contacto con \u00e9l, porque no pod\u00edas conocerle sin quererle. Todos compartimos el dolor de su familia, reunida en torno a Brigitte, su \u00edntima esposa, y sus hijos. Nacido en T\u00fanez el 3 de noviembre de 1941, estudi\u00f3 brillantemente en el Liceo Carnot de T\u00fanez, y despu\u00e9s en Par\u00eds, en el Liceo Henri IV, como \u00e9l mismo record\u00f3 recientemente al rendir homenaje a su compa\u00f1ero de estudios de filosof\u00eda, Paul Tavernier. Tras estudiar en la Facultad de Derecho y en Sciences Po, Jean-Paul Costa ingres\u00f3 en la ENA, en la clase Montesquieu, todo un programa para este gran liberal que encontr\u00f3 sus ra\u00edces en la Dordo\u00f1a. Su carrera en el Conseil d&#8217;Etat altern\u00f3 responsabilidades contenciosas y administrativas, sobre todo en el \u00e1mbito a\u00fan nuevo del derecho inform\u00e1tico, que le puso en contacto por primera vez con el Consejo de Europa. Cuando el gobierno cambi\u00f3 de manos en 1981, se convirti\u00f3 en jefe de gabinete de Alain Savary en el Ministerio de Educaci\u00f3n, antes de volver al Palacio Real en 1984 como ponente general de la secci\u00f3n de estudios e informes, y despu\u00e9s como secretario general del Instituto Franc\u00e9s de Ciencias Administrativas. Tambi\u00e9n fue presidente de la Comisi\u00f3n de Acceso a los Documentos Administrativos (CADA). Al mismo tiempo, sigui\u00f3 ense\u00f1ando <em>\u00ablibertades p\u00fablicas <\/em>\u00ab, como profesor asociado en la Universidad de Orleans y luego en la Universidad de Par\u00eds I. La creaci\u00f3n del \u00abnuevo\u00bb Tribunal Europeo de Derechos Humanos, tras la entrada en vigor del Protocolo n\u00ba 11 en noviembre de 1998, marc\u00f3 un giro decisivo en su vida, al ser elegido juez en representaci\u00f3n de Francia en 1998. Form\u00f3 parte del Tribunal hasta noviembre de 2011. Otros se\u00f1alar\u00e1n su influencia intelectual y su impacto en la pol\u00edtica jur\u00eddica del Tribunal de Estrasburgo, primero como juez y luego como Presidente del Tribunal desde noviembre de 2006. \u00c9l mismo relat\u00f3 con demasiada modestia su experiencia \u00fanica en un libro de memorias jur\u00eddicas sobre <em>el Tribunal Europeo de Derechos Humanos: Des juges pour la libert\u00e9<\/em> (Dalloz, 2013, 1\u00aa ed.). Pero esta longevidad excepcional es una muestra de la confianza de sus compa\u00f1eros, en un momento en que el Tribunal ya se enfrentaba a muchos retos.      <\/p>\n<p>     Al tiempo que garantizaba la coherencia de una jurisprudencia aplicable a una Europa ampliada a las nuevas democracias, el presidente Costa fue capaz de inventar la \u00abdiplomacia judicial\u00bb para permitir la entrada en vigor del Protocolo n\u00ba 14, una reforma indispensable para gestionar a tiempo un contencioso de gran envergadura, a pesar de la larga obstrucci\u00f3n de Rusia. Es significativo que uno de los \u00faltimos art\u00edculos publicados por Jean-Paul Costa en la <em>Revue trimestrielle des droits de l&#8217;homme<\/em> fuera una l\u00facida evaluaci\u00f3n de \u00ablas consecuencias de la salida de Rusia del Consejo de Europa\u00bb (2023\/1). Jean-Paul Costa se hab\u00eda convertido en un ciudadano adoptivo de Estrasburgo, muy activo en los c\u00edrculos culturales, pero su compromiso no pod\u00eda detenerse ah\u00ed. Durante casi diez a\u00f1os fue Presidente del Instituto Internacional de Derechos Humanos, que transform\u00f3 en la Fundaci\u00f3n Ren\u00e9 Cassin y dirigi\u00f3 con mano segura, contribuyendo a la transmisi\u00f3n de una concepci\u00f3n francesa y universal de los derechos humanos heredada de Ren\u00e9 Cassin, que antes que \u00e9l hab\u00eda sido el primer jurista franc\u00e9s en llegar a ser Presidente del Tribunal Europeo de Derechos Humanos. Basta decir que le resultaban profundamente ofensivos los ataques a <em>los \u00abderechos humanos\u00bb<\/em> o las nuevas formas de macartismo, que convert\u00edan al Tribunal de Estrasburgo en chivo expiatorio de todos los males de la sociedad. Rechazaba la amalgama demag\u00f3gica de un \u00abgobierno de jueces\u00bb, donde no hay Estado sin ley ni derechos sin garant\u00eda de derechos. Lejos de cualquier optimismo de mando u oportunismo cediendo a los efectos de la moda, permaneci\u00f3 muy apegado a una vieja tradici\u00f3n republicana en la que el principio de laicidad era garante de la paz civil, sin restar nada a las convicciones religiosas de cada individuo. Lejos del relativismo cultural, no opuso una concepci\u00f3n europea de los derechos humanos encerrada en s\u00ed misma a una visi\u00f3n universal arraigada en los principios y objetivos de la Carta de las Naciones Unidas. El propio Convenio Europeo de Derechos Humanos afirma que <em>\u00ablas libertades fundamentales son el fundamento mismo de la justicia y de la paz\u00bb. <\/em>Durante casi 25 a\u00f1os, en Estrasburgo, en el seno del Tribunal y despu\u00e9s al frente de la Fundaci\u00f3n, el Presidente Jean-Paul Costa ha servido a este ideal con un valor, una abnegaci\u00f3n y una entereza ante las pruebas y los ataques que hoy inspiran un respeto un\u00e1nime. Hombre de s\u00edntesis, echamos de menos su fuerza de convicci\u00f3n, su sinceridad y su tolerancia en estos tiempos de crisis. Pero con la firme determinaci\u00f3n de permanecer fiel a su obra, la Fundaci\u00f3n Ren\u00e9 Cassin se propone proseguir su acci\u00f3n al servicio de los derechos humanos, en todas partes y para todos. <\/p>\n<p>&nbsp;<\/p>\n<p>Emmanuel Decaux, <i>Presidente de la Fundaci\u00f3n <\/i> <i>Ren\u00e9 Cassin<\/i> S\u00e9bastien Touz\u00e9, <i>Director de la Fundaci\u00f3n Ren\u00e9 Cassin<\/i> <\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>JEAN-PAUL COSTA (1941-2023) El fallecimiento de Jean-Paul-Costa, el 27 de  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":5670,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[],"class_list":["post-4977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicados-de-prensa-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fallecimiento del Presidente Jean-Paul Costa - Fondation Ren\u00e9 CASSIN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fallecimiento del Presidente Jean-Paul Costa - Fondation Ren\u00e9 CASSIN\" \/>\n<meta property=\"og:description\" content=\"JEAN-PAUL COSTA (1941-2023) El fallecimiento de Jean-Paul-Costa, el 27 de [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Ren\u00e9 CASSIN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FondationReneCassin\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-28T05:06:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T13:17:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iidh.org\/wp-content\/uploads\/2023\/04\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"390\" \/>\n\t<meta property=\"og:image:height\" content=\"586\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"iidh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IIDHStrasbourg\" \/>\n<meta name=\"twitter:site\" content=\"@IIDHStrasbourg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"iidh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/\"},\"author\":{\"name\":\"iidh\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#\\\/schema\\\/person\\\/b11ebaff7344b9379adfa42046c36b7b\"},\"headline\":\"Fallecimiento del Presidente Jean-Paul Costa\",\"datePublished\":\"2023-04-28T05:06:57+00:00\",\"dateModified\":\"2024-11-08T13:17:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/\"},\"wordCount\":1012,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iidh.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg\",\"articleSection\":[\"Comunicados de prensa \\\/ Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/\",\"url\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/\",\"name\":\"Fallecimiento del Presidente Jean-Paul Costa - Fondation Ren\u00e9 CASSIN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iidh.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg\",\"datePublished\":\"2023-04-28T05:06:57+00:00\",\"dateModified\":\"2024-11-08T13:17:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iidh.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iidh.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg\",\"width\":390,\"height\":586,\"caption\":\"Hommage \u00e0 notre Pr\u00e9sident Jean-Paul Costa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/fallecimiento-del-presidente-jean-paul-costa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fallecimiento del Presidente Jean-Paul Costa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/\",\"name\":\"Fondation Ren\u00e9 CASSIN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#organization\",\"name\":\"Fondation Ren\u00e9 CASSIN\",\"url\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iidh.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/LOGO_FRC-rouge.svg\",\"contentUrl\":\"https:\\\/\\\/www.iidh.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/LOGO_FRC-rouge.svg\",\"width\":699,\"height\":221,\"caption\":\"Fondation Ren\u00e9 CASSIN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FondationReneCassin\\\/\",\"https:\\\/\\\/x.com\\\/IIDHStrasbourg\",\"https:\\\/\\\/www.instagram.com\\\/fondationrenecassin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iidh.org\\\/es\\\/#\\\/schema\\\/person\\\/b11ebaff7344b9379adfa42046c36b7b\",\"name\":\"iidh\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fallecimiento del Presidente Jean-Paul Costa - Fondation Ren\u00e9 CASSIN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/","og_locale":"es_ES","og_type":"article","og_title":"Fallecimiento del Presidente Jean-Paul Costa - Fondation Ren\u00e9 CASSIN","og_description":"JEAN-PAUL COSTA (1941-2023) El fallecimiento de Jean-Paul-Costa, el 27 de [...]","og_url":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/","og_site_name":"Fondation Ren\u00e9 CASSIN","article_publisher":"https:\/\/www.facebook.com\/FondationReneCassin\/","article_published_time":"2023-04-28T05:06:57+00:00","article_modified_time":"2024-11-08T13:17:24+00:00","og_image":[{"width":390,"height":586,"url":"https:\/\/www.iidh.org\/wp-content\/uploads\/2023\/04\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg","type":"image\/jpeg"}],"author":"iidh","twitter_card":"summary_large_image","twitter_creator":"@IIDHStrasbourg","twitter_site":"@IIDHStrasbourg","twitter_misc":{"Escrito por":"iidh","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/#article","isPartOf":{"@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/"},"author":{"name":"iidh","@id":"https:\/\/www.iidh.org\/es\/#\/schema\/person\/b11ebaff7344b9379adfa42046c36b7b"},"headline":"Fallecimiento del Presidente Jean-Paul Costa","datePublished":"2023-04-28T05:06:57+00:00","dateModified":"2024-11-08T13:17:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/"},"wordCount":1012,"commentCount":0,"publisher":{"@id":"https:\/\/www.iidh.org\/es\/#organization"},"image":{"@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iidh.org\/wp-content\/uploads\/2023\/04\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg","articleSection":["Comunicados de prensa \/ Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/","url":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/","name":"Fallecimiento del Presidente Jean-Paul Costa - Fondation Ren\u00e9 CASSIN","isPartOf":{"@id":"https:\/\/www.iidh.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/#primaryimage"},"image":{"@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iidh.org\/wp-content\/uploads\/2023\/04\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg","datePublished":"2023-04-28T05:06:57+00:00","dateModified":"2024-11-08T13:17:24+00:00","breadcrumb":{"@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/#primaryimage","url":"https:\/\/www.iidh.org\/wp-content\/uploads\/2023\/04\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg","contentUrl":"https:\/\/www.iidh.org\/wp-content\/uploads\/2023\/04\/390px-Jean-Paul_Costa_par_Claude_Truong-Ngoc_mai_2013-1.jpg","width":390,"height":586,"caption":"Hommage \u00e0 notre Pr\u00e9sident Jean-Paul Costa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iidh.org\/es\/fallecimiento-del-presidente-jean-paul-costa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.iidh.org\/es\/"},{"@type":"ListItem","position":2,"name":"Fallecimiento del Presidente Jean-Paul Costa"}]},{"@type":"WebSite","@id":"https:\/\/www.iidh.org\/es\/#website","url":"https:\/\/www.iidh.org\/es\/","name":"Fondation Ren\u00e9 CASSIN","description":"","publisher":{"@id":"https:\/\/www.iidh.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iidh.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.iidh.org\/es\/#organization","name":"Fondation Ren\u00e9 CASSIN","url":"https:\/\/www.iidh.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iidh.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.iidh.org\/wp-content\/uploads\/2024\/09\/LOGO_FRC-rouge.svg","contentUrl":"https:\/\/www.iidh.org\/wp-content\/uploads\/2024\/09\/LOGO_FRC-rouge.svg","width":699,"height":221,"caption":"Fondation Ren\u00e9 CASSIN"},"image":{"@id":"https:\/\/www.iidh.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FondationReneCassin\/","https:\/\/x.com\/IIDHStrasbourg","https:\/\/www.instagram.com\/fondationrenecassin\/"]},{"@type":"Person","@id":"https:\/\/www.iidh.org\/es\/#\/schema\/person\/b11ebaff7344b9379adfa42046c36b7b","name":"iidh"}]}},"_links":{"self":[{"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/posts\/4977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/comments?post=4977"}],"version-history":[{"count":1,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/posts\/4977\/revisions"}],"predecessor-version":[{"id":5612,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/posts\/4977\/revisions\/5612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/media\/5670"}],"wp:attachment":[{"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/media?parent=4977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/categories?post=4977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iidh.org\/es\/wp-json\/wp\/v2\/tags?post=4977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}